{"id":253,"date":"2013-07-17T13:05:33","date_gmt":"2013-07-17T11:05:33","guid":{"rendered":"http:\/\/www.angebotssoftware.net\/blog\/?p=253"},"modified":"2024-11-13T14:12:14","modified_gmt":"2024-11-13T13:12:14","slug":"uberraschend-freundliche-software","status":"publish","type":"post","link":"https:\/\/getgrip.de\/blog\/uberraschend-freundliche-software\/","title":{"rendered":"\u00dcberraschend freundliche Software"},"content":{"rendered":"<p>Zur Abwechslung mal ein kurzer Abstecher ins Reich der User Experience (UX). Ich liebe es, wenn mich Software mit kleinen Arbeitserleichterungen oder Aufmerksamkeiten \u00fcberrascht. Daher schaue ich mir immer wieder gerne die Dinge an, die bei\u00a0<a href=\"http:\/\/littlebigdetails.com\">Little Big Details<\/a>\u00a0zusammengetragen werden. Gelegentlich mache ich aber auch selbst Entdeckungen.<\/p>\n<p>Heute habe ich in einem US-Onlinestore (basierend auf Shopify) rumgeklickt. Ich wollte die Versandkosten nach Deutschland sehen. L\u00e4nderliste ist im Fokus, dann vier mal &#8222;g&#8220; dr\u00fccken: 1, 2, 3, 4: Gabon, Gambia, Georgia, Germany. So mache ich das eigentlich immer.<\/p>\n<p>Dann habe ich abgebrochen und weiter gest\u00f6bert. Anschlie\u00dfend zur\u00fcck zur Kasse. L\u00e4nderliste im Fokus; Gerade setzte ich zum Schnellfeuern der G-Taste an, da kam &#8222;Germany&#8220; schon nach dem ersten Tastendruck. Shopify hat sich meine vorherige Auswahl gemerkt und diese vor die eigentliche L\u00e4nderliste gestellt.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-255 aligncenter\" src=\"\/blog\/wp-content\/uploads\/2013\/07\/shopify_countries.png\" alt=\"shopify_countries\" width=\"764\" height=\"455\" \/><\/p>\n<p>Ein \u00e4hnliches Erlebnis hatte ich vor Kurzem mit Google Chrome: im Bookmark-Manager einen neuen Ordner angelegt. Beim n\u00e4chsten Bookmark ist dieser Ordner vorausgew\u00e4hlt. Sehr praktisch. Von Safari war ich mehr Klickerei gew\u00f6hnt.<\/p>\n<p>Beides sind wirklich nur Kleinigkeiten, aber ich habe mich \u00fcber die Geste gefreut, vielleicht auch weil sie unerwartet kam. \ud83d\ude42 Bei mir jedenfalls haben sowohl Chrome als auch Shopify Pluspunkte gesammelt.<\/p>\n<p>Und das ist der tiefer liegende Sinn: solche unerwarteten kleinen Nettigkeiten wecken positive Emotionen. Und eine positive Benutzererfahrung (UX) st\u00e4rkt die Kundenbindung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zur Abwechslung mal ein kurzer Abstecher ins Reich der User Experience (UX). Ich liebe es, wenn mich Software mit kleinen Arbeitserleichterungen oder Aufmerksamkeiten \u00fcberrascht. Daher schaue ich mir immer wieder (&hellip;) <a href=\"https:\/\/getgrip.de\/blog\/uberraschend-freundliche-software\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[16,15,29],"class_list":["post-253","post","type-post","status-publish","format-standard","hentry","category-webdesign-marketing","tag-emotionen","tag-kundenbindung","tag-ux"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00dcberraschend freundliche Software - Grip Blog - Professionelle Angebote schreiben. In Rekordzeit.<\/title>\n<meta name=\"description\" content=\"Eine positive Benutzererfahrung (UX) st\u00e4rkt die Kundenbindung: zwei Beispiele\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/getgrip.de\/blog\/uberraschend-freundliche-software\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00dcberraschend freundliche Software - Grip Blog - Professionelle Angebote schreiben. In Rekordzeit.\" \/>\n<meta property=\"og:description\" content=\"Eine positive Benutzererfahrung (UX) st\u00e4rkt die Kundenbindung: zwei Beispiele\" \/>\n<meta property=\"og:url\" content=\"https:\/\/getgrip.de\/blog\/uberraschend-freundliche-software\/\" \/>\n<meta property=\"og:site_name\" content=\"Grip Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grip.angebotssoftware\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/grip.angebotssoftware\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-17T11:05:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-13T13:12:14+00:00\" \/>\n<meta name=\"author\" content=\"Till\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@till_otto\" \/>\n<meta name=\"twitter:site\" content=\"@grip_app\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Till\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/uberraschend-freundliche-software\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/uberraschend-freundliche-software\\\/\"},\"author\":{\"name\":\"Till\",\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/#\\\/schema\\\/person\\\/50f29e3e3c20f6ef95d856e2e3800271\"},\"headline\":\"\u00dcberraschend freundliche Software\",\"datePublished\":\"2013-07-17T11:05:33+00:00\",\"dateModified\":\"2024-11-13T13:12:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/uberraschend-freundliche-software\\\/\"},\"wordCount\":227,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/#organization\"},\"keywords\":[\"emotionen\",\"Kundenbindung\",\"UX\"],\"articleSection\":[\"Marketing\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/getgrip.de\\\/blog\\\/uberraschend-freundliche-software\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/uberraschend-freundliche-software\\\/\",\"url\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/uberraschend-freundliche-software\\\/\",\"name\":\"\u00dcberraschend freundliche Software - Grip Blog - Professionelle Angebote schreiben. In Rekordzeit.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/#website\"},\"datePublished\":\"2013-07-17T11:05:33+00:00\",\"dateModified\":\"2024-11-13T13:12:14+00:00\",\"description\":\"Eine positive Benutzererfahrung (UX) st\u00e4rkt die Kundenbindung: zwei Beispiele\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/getgrip.de\\\/blog\\\/uberraschend-freundliche-software\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/\",\"name\":\"Grip Blog\",\"description\":\"Professionelle Angebote schreiben. In Rekordzeit.\",\"publisher\":{\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/#organization\",\"name\":\"Grip by T8 Lab GmbH\",\"url\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/grip_inverse_sm.png\",\"contentUrl\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/grip_inverse_sm.png\",\"width\":200,\"height\":51,\"caption\":\"Grip by T8 Lab GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/grip.angebotssoftware\",\"https:\\\/\\\/x.com\\\/grip_app\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/#\\\/schema\\\/person\\\/50f29e3e3c20f6ef95d856e2e3800271\",\"name\":\"Till\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f7ba97ed860e69dc3929a8be0690ef648f87ebbc6a181bf1aabefcc51524d73?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f7ba97ed860e69dc3929a8be0690ef648f87ebbc6a181bf1aabefcc51524d73?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f7ba97ed860e69dc3929a8be0690ef648f87ebbc6a181bf1aabefcc51524d73?s=96&d=mm&r=g\",\"caption\":\"Till\"},\"description\":\"Till Otto ist der Gr\u00fcnder von Grip und seit \u00fcber 10 Jahren als Softwareentwickler und Berater selbst\u00e4ndig.\",\"sameAs\":[\"https:\\\/\\\/getgrip.de\\\/?utm_source=asnet&amp;utm_medium=blog&amp;utm_content=author&amp;utm\",\"https:\\\/\\\/www.facebook.com\\\/grip.angebotssoftware\",\"https:\\\/\\\/x.com\\\/till_otto\"],\"url\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/author\\\/till\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00dcberraschend freundliche Software - Grip Blog - Professionelle Angebote schreiben. In Rekordzeit.","description":"Eine positive Benutzererfahrung (UX) st\u00e4rkt die Kundenbindung: zwei Beispiele","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/getgrip.de\/blog\/uberraschend-freundliche-software\/","og_locale":"de_DE","og_type":"article","og_title":"\u00dcberraschend freundliche Software - Grip Blog - Professionelle Angebote schreiben. In Rekordzeit.","og_description":"Eine positive Benutzererfahrung (UX) st\u00e4rkt die Kundenbindung: zwei Beispiele","og_url":"https:\/\/getgrip.de\/blog\/uberraschend-freundliche-software\/","og_site_name":"Grip Blog","article_publisher":"https:\/\/www.facebook.com\/grip.angebotssoftware","article_author":"https:\/\/www.facebook.com\/grip.angebotssoftware","article_published_time":"2013-07-17T11:05:33+00:00","article_modified_time":"2024-11-13T13:12:14+00:00","author":"Till","twitter_card":"summary_large_image","twitter_creator":"@till_otto","twitter_site":"@grip_app","twitter_misc":{"Verfasst von":"Till","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/getgrip.de\/blog\/uberraschend-freundliche-software\/#article","isPartOf":{"@id":"https:\/\/getgrip.de\/blog\/uberraschend-freundliche-software\/"},"author":{"name":"Till","@id":"https:\/\/getgrip.de\/blog\/#\/schema\/person\/50f29e3e3c20f6ef95d856e2e3800271"},"headline":"\u00dcberraschend freundliche Software","datePublished":"2013-07-17T11:05:33+00:00","dateModified":"2024-11-13T13:12:14+00:00","mainEntityOfPage":{"@id":"https:\/\/getgrip.de\/blog\/uberraschend-freundliche-software\/"},"wordCount":227,"commentCount":0,"publisher":{"@id":"https:\/\/getgrip.de\/blog\/#organization"},"keywords":["emotionen","Kundenbindung","UX"],"articleSection":["Marketing"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/getgrip.de\/blog\/uberraschend-freundliche-software\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/getgrip.de\/blog\/uberraschend-freundliche-software\/","url":"https:\/\/getgrip.de\/blog\/uberraschend-freundliche-software\/","name":"\u00dcberraschend freundliche Software - Grip Blog - Professionelle Angebote schreiben. In Rekordzeit.","isPartOf":{"@id":"https:\/\/getgrip.de\/blog\/#website"},"datePublished":"2013-07-17T11:05:33+00:00","dateModified":"2024-11-13T13:12:14+00:00","description":"Eine positive Benutzererfahrung (UX) st\u00e4rkt die Kundenbindung: zwei Beispiele","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/getgrip.de\/blog\/uberraschend-freundliche-software\/"]}]},{"@type":"WebSite","@id":"https:\/\/getgrip.de\/blog\/#website","url":"https:\/\/getgrip.de\/blog\/","name":"Grip Blog","description":"Professionelle Angebote schreiben. In Rekordzeit.","publisher":{"@id":"https:\/\/getgrip.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/getgrip.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/getgrip.de\/blog\/#organization","name":"Grip by T8 Lab GmbH","url":"https:\/\/getgrip.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/getgrip.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/getgrip.de\/blog\/wp-content\/uploads\/2016\/01\/grip_inverse_sm.png","contentUrl":"https:\/\/getgrip.de\/blog\/wp-content\/uploads\/2016\/01\/grip_inverse_sm.png","width":200,"height":51,"caption":"Grip by T8 Lab GmbH"},"image":{"@id":"https:\/\/getgrip.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/grip.angebotssoftware","https:\/\/x.com\/grip_app"]},{"@type":"Person","@id":"https:\/\/getgrip.de\/blog\/#\/schema\/person\/50f29e3e3c20f6ef95d856e2e3800271","name":"Till","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5f7ba97ed860e69dc3929a8be0690ef648f87ebbc6a181bf1aabefcc51524d73?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5f7ba97ed860e69dc3929a8be0690ef648f87ebbc6a181bf1aabefcc51524d73?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f7ba97ed860e69dc3929a8be0690ef648f87ebbc6a181bf1aabefcc51524d73?s=96&d=mm&r=g","caption":"Till"},"description":"Till Otto ist der Gr\u00fcnder von Grip und seit \u00fcber 10 Jahren als Softwareentwickler und Berater selbst\u00e4ndig.","sameAs":["https:\/\/getgrip.de\/?utm_source=asnet&amp;utm_medium=blog&amp;utm_content=author&amp;utm","https:\/\/www.facebook.com\/grip.angebotssoftware","https:\/\/x.com\/till_otto"],"url":"https:\/\/getgrip.de\/blog\/author\/till\/"}]}},"_links":{"self":[{"href":"https:\/\/getgrip.de\/blog\/wp-json\/wp\/v2\/posts\/253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/getgrip.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/getgrip.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/getgrip.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/getgrip.de\/blog\/wp-json\/wp\/v2\/comments?post=253"}],"version-history":[{"count":15,"href":"https:\/\/getgrip.de\/blog\/wp-json\/wp\/v2\/posts\/253\/revisions"}],"predecessor-version":[{"id":1807,"href":"https:\/\/getgrip.de\/blog\/wp-json\/wp\/v2\/posts\/253\/revisions\/1807"}],"wp:attachment":[{"href":"https:\/\/getgrip.de\/blog\/wp-json\/wp\/v2\/media?parent=253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/getgrip.de\/blog\/wp-json\/wp\/v2\/categories?post=253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/getgrip.de\/blog\/wp-json\/wp\/v2\/tags?post=253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}