{"id":447,"date":"2014-01-04T01:11:16","date_gmt":"2014-01-03T23:11:16","guid":{"rendered":"http:\/\/www.angebotssoftware.net\/blog\/?p=447"},"modified":"2024-11-13T14:13:53","modified_gmt":"2024-11-13T13:13:53","slug":"aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet","status":"publish","type":"post","link":"https:\/\/getgrip.de\/blog\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\/","title":{"rendered":"Aufgabenverwaltung: mit Trello in wenigen Schritten zu mehr Produktivit\u00e4t"},"content":{"rendered":"<p>Die selbst\u00e4ndige\u00a0T\u00e4tigkeit bringt einerseits Freiheit, andererseits auch eine besondere Verantwortung mit sich. Wir alle m\u00fcssen jeden Tag zahlreiche Aufgaben bew\u00e4ltigen. Eine funktionsf\u00e4hige Aufgabenverwaltung zu haben, ist f\u00fcr die Arbeit als Selbst\u00e4ndiger essenziell.<\/p>\n<p>In den letzten Jahren habe ich meine Aufgaben mit Hilfe diverser Tools verwaltet. Mit mittelm\u00e4\u00dfigem Erfolg, wie ich fand. Vieles hat gut funktioniert, aber irgendwo gab es immer Ecken und Kanten, die einen reibungslosen Arbeitsablauf behinderten.<\/p>\n<p>Seit einigen Wochen habe ich nun einen Workflow im Einsatz, der funktioniert. Was hei\u00dft das?<\/p>\n<ol>\n<li>Die Aufgaben werden erledigt.<\/li>\n<li>Es bleibt nichts liegen.<\/li>\n<li>Es macht mir Spa\u00df, meine Aktivit\u00e4ten damit zu verwalten.<\/li>\n<\/ol>\n<p>F\u00fcr mich ist das ein gro\u00dfer Fortschritt. Ich behaupte nicht, dass diese Arbeitsweise die perfekte L\u00f6sung f\u00fcr jeden ist. Aber ich hoffe, dass Du zumindest Anregungen f\u00fcr Deine eigene Aufgabenverwaltung aus meiner Schilderung ziehen kannst. Und wenn Du mit Deiner aktuellen Vorgehensweise unzufrieden bist, probiere es doch einfach mal aus.<\/p>\n<p><!--more--><\/p>\n<h2>Einrichtung<\/h2>\n<p>Ich verwalte meine Aktivit\u00e4ten mit <a title=\"Trello\" href=\"http:\/\/trello.com\" target=\"_blank\" rel=\"noopener\">Trello<\/a>; auf dem Desktop per Browser, was wahrscheinlich 95% meiner Nutzung ausmacht, unterwegs per App. Letztere gibt es <a title=\"Trello f\u00fcr Android\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.trello\" target=\"_blank\" rel=\"noopener\">f\u00fcr Android<\/a> und <a title=\"Trello f\u00fcr iOS\" href=\"https:\/\/itunes.apple.com\/de\/app\/trello-organize-anything\/id461504587?mt=8\" target=\"_blank\" rel=\"noopener\">f\u00fcr iOS<\/a>. Die Benutzeroberfl\u00e4chen sind jeweils durchdacht und lassen sich angenehm bedienen.<\/p>\n<p>Trello strukturiert Aufgaben in der folgenden Hierarchie:<\/p>\n<ul>\n<li>Boards<\/li>\n<li>Listen<\/li>\n<li>Karten<\/li>\n<\/ul>\n<div id=\"attachment_691\" style=\"width: 1450px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/getgrip.de\/blog\/wp-content\/uploads\/2015\/11\/trello_board.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-691\" class=\"  wp-image-691 size-full\" title=\"Trello: Hauptansicht eines Boards mit Listen und Karten\" src=\"https:\/\/getgrip.de\/blog\/wp-content\/uploads\/2015\/11\/trello_board.png\" alt=\"Trello: Hauptansicht eines Boards\" width=\"1440\" height=\"651\" \/><\/a><p id=\"caption-attachment-691\" class=\"wp-caption-text\">Trello<\/p><\/div>\n<h2>Brett<\/h2>\n<p>Lege ein neues Board an und gib ihm einen Namen wie z.B. &#8222;Aufgaben&#8220;. Nat\u00fcrlich kannst Du auch etwas Kreativeres verwenden. Ein Board enth\u00e4lt verschiedene Listen, die einzelne Aufgaben in Form von Karten aufnehmen.<\/p>\n<h2>Listen<\/h2>\n<p>Jetzt legst Du sieben Listen an:<\/p>\n<ol>\n<li>\u00dcberblick<\/li>\n<li>Eingangskorb<\/li>\n<li>Heute<\/li>\n<li>Erledigt<\/li>\n<li>Diese Woche<\/li>\n<li>Sp\u00e4ter<\/li>\n<li>Wartet auf&#8230;<\/li>\n<\/ol>\n<p>Die Liste mit dem Namen &#8222;\u00dcberblick&#8220; ist anders als die anderen und nimmt Deine wichtigsten &#8222;Baustellen&#8220; und Ziele auf. Ich habe hier f\u00fcnf Eintr\u00e4ge drin stehen: einen f\u00fcr Pers\u00f6nliches und vier f\u00fcr berufliche Ziele. Das sind langfristige Ziele, die nicht trivial zu erledigen oder zu erreichen sind. Deine aktiven Webdesign- oder Webentwicklungsprojekte sind hier ebenfalls gut aufgehoben. Die Eintr\u00e4ge im \u00dcberblick dienen als Kategorien, denen sp\u00e4ter einzelne Todos zugeordnet werden, um im allt\u00e4glichen Chaos das Ziel am Horizont nicht aus den Augen zu verlieren.<\/p>\n<p>Du legst also f\u00fcr die vier bis sieben wichtigsten Themen in Deinem Leben jeweils eine Karte an. Das k\u00f6nnte sein: Gesch\u00e4ft, Pers\u00f6nlich, &lt;Projekt 1&gt;, &lt;Projekt 2&gt;, Wartung etc. Es sollten nicht mehr als sieben und nur wichtige Themen sein, um tats\u00e4chlich den \u00dcberblick zu behalten.<\/p>\n<p>Dann klickst Du auf die erste Karte. Dadurch wird die Karte umgedreht und diverse Details werden zug\u00e4nglich. Klicke auf &#8222;Label&#8220; und w\u00e4hle eine Farbe f\u00fcr das Thema. Das wiederholst Du f\u00fcr die anderen Themenkomplexe. Alternativ kannst Du mit der Maus \u00fcber die Karte in der Liste fahren, die Taste &#8222;L&#8220; und anschlie\u00dfend die gew\u00fcnschte Ziffer dr\u00fccken.<\/p>\n<h2>Aufgaben<\/h2>\n<p>Neue Aufgaben kommen grunds\u00e4tzlich zuerst in den Eingangskorb. Einzige Ausnahme: es ist sofort und *ohne nachzudenken* klar, dass Du sie noch am selben Tag erledigen willst oder musst (&#8222;Ich muss heute noch unbedingt &#8230;&#8220;). Im Normalfall wirfst Du neue Aufgaben in den Eingangskorb und denkst bei der n\u00e4chsten Planung dar\u00fcber nach, wann sie zu erledigen ist. Diese Aufteilung in Sammeln und Planen sorgt f\u00fcr eine Entlastung des Gehirns und eine bessere Planung.<\/p>\n<h2>Die Aufgabenverwaltung<\/h2>\n<p>Zu Beginn eines jeden Arbeitstags schaue ich den Eingangskorb durch und verteile alle Karten auf die anderen Listen. Nach &#8222;Heute&#8220; kommen alle, die ich heute erledigen will. Auf die Liste &#8222;Diese Woche&#8220; kommt alles, was diese Woche erledigt werden muss und in &#8222;Sp\u00e4ter&#8220; alles, was mehr Zeit hat. Bei dieser Gelegenheit pr\u00fcfe ich auch, ob die Eintr\u00e4ge in den anderen Listen noch stimmen. Au\u00dferdem ordne ich die Aufgaben einer Kategorie aus dem &#8222;\u00dcberblick&#8220; zu (sofern eine passende vorhanden ist).<\/p>\n<p>Wenn ich eine Aufgabe erledigt habe, verschiebe ich sie nach (\u00dcberraschung!) &#8222;Erledigt&#8220;. In der n\u00e4chsten Planungsrunde archiviere ich alle Karten der Liste &#8222;Erledigt&#8220;, sodass diese wieder leer ist. Das geht in einem Rutsch \u00fcber das Men\u00fc zur Liste.<\/p>\n<div id=\"attachment_448\" style=\"width: 537px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-448\" class=\"wp-image-448 \" title=\"Trello: Alle Karten einer Liste archivieren\" src=\"\/blog\/wp-content\/uploads\/2014\/01\/trello_archive_all.png\" alt=\"Trello-Screenshot (Alle Karten einer Liste archivieren)\" width=\"527\" height=\"324\" \/><p id=\"caption-attachment-448\" class=\"wp-caption-text\">Trello: Alle Karten einer Liste archivieren<\/p><\/div>\n<p>Ben\u00f6tige ich die Zuarbeit von Dritten, kommt die Aufgabe in die Liste &#8222;Wartet auf&#8230;&#8220;, damit sie nicht die anderen Listen verstopft.<\/p>\n<h2>Aufgaben per E-Mail einstellen<\/h2>\n<p>Vieles von dem, was wir erledigen m\u00fcssen, kommt in Form einer Email bei uns an. Daher habe ich lange Zeit einen Teil meiner Aufgaben in meinem Mailprogramm &#8222;verwaltet&#8220;. Das funktioniert nat\u00fcrlich nicht besonders gut.<\/p>\n<div id=\"attachment_450\" style=\"width: 312px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-450\" class=\"size-full wp-image-450\" src=\"\/blog\/wp-content\/uploads\/2014\/01\/trello_mail.png\" alt=\"Trello-Screenshot (Trello E-Mail-Adresse eines Boards)\" width=\"302\" height=\"549\" \/><p id=\"caption-attachment-450\" class=\"wp-caption-text\">Trello E-Mail-Adresse eines Boards<\/p><\/div>\n<p>Aber Trello bietet hier Abhilfe: jedes Board hat eine eigene E-Mail-Adresse. Unter (Show Sidebar) Menu \/ Settings \/ Email Settings kannst Du die Adresse sehen und einstellen, in welche Liste neue Aufgaben per E-Mail einsortiert werden. Hier w\u00e4hlst Du &#8222;Eingangskorb&#8220;. Die E-Mail-Adresse legst Du am besten in Deinem Adressbuch ab, damit Du sie griffbereit hast.<\/p>\n<p>Damit kannst Du Mails an Dein Trello-Board weiterleiten und sie tauchen automatisch als neue Karte in Deinem Eingangskorb auf. Die Bezeichnung wird \u00fcbrigens aus dem Betreff \u00fcbernommen, der Mailinhalt kommt in die Beschreibung der Karte. F\u00fcr mich ist dies ein immens wichtiges Feature einer Aufgabenverwaltung.<\/p>\n<h2>Mehr<\/h2>\n<p>Trello kann noch einiges mehr, worauf ich nicht im Detail eingehe, weil ich meine Arbeitsweise vorstellen wollte und nicht so sehr das Tool. Der Vollst\u00e4ndigkeit halber sei aber erw\u00e4hnt, dass Trello u.a. auch F\u00e4lligkeiten, Checklisten, Anh\u00e4nge, sowie das gemeinsame Bearbeiten mit anderen Nutzern unterst\u00fctzt.<\/p>\n<h2>Fazit<\/h2>\n<p>Seit \u00fcber zwei Monaten habe ich die vorgestellte Arbeitsweise nun aktiv im Einsatz und nutze sie weiterhin gerne. Das ist f\u00fcr mich der entscheidende Punkt: weil die Aufgabenverwaltung Spa\u00df macht, kommt sie zum Einsatz und dadurch entfaltet sie ihren Nutzen.<\/p>\n<p>\u00dcbrigens, das meiste von dem, was ich in diesem Artikel als &#8222;meine Arbeitsweise&#8220; vorstelle, stammt nicht von mir, sondern wurde aus diversen Quellen zusammengestellt und an meine pers\u00f6nlichen Bed\u00fcrfnisse angepasst. Mein besonderer Dank gilt Tim Maurer, dessen <a href=\"http:\/\/www.forbes.com\/sites\/timmaurer\/2013\/11\/21\/7-steps-to-creating-the-best-personal-task-management-system-with-trello\">Artikel<\/a> mich inspiriert hat, meine eigene Vorgehensweise zu finden.<\/p>\n<p>Wie verwaltest Du Deine Aufgaben? Welche Erfahrungen hast Du damit gemacht? Ich freue mich \u00fcber jeden Kommentar und ganz besonders, wenn es um Deine Erfahrungen, Anpassungen und Verbesserungen geht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die selbst\u00e4ndige\u00a0T\u00e4tigkeit bringt einerseits Freiheit, andererseits auch eine besondere Verantwortung mit sich. Wir alle m\u00fcssen jeden Tag zahlreiche Aufgaben bew\u00e4ltigen. Eine funktionsf\u00e4hige Aufgabenverwaltung zu haben, ist f\u00fcr die Arbeit als (&hellip;) <a href=\"https:\/\/getgrip.de\/blog\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-447","post","type-post","status-publish","format-standard","hentry","category-selbstaendigkeit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aufgabenverwaltung: mehr Produktivit\u00e4t f\u00fcr selbst\u00e4ndige Webdesigner<\/title>\n<meta name=\"description\" content=\"Eine zuverl\u00e4ssige Aufgabenverwaltung zu haben, ist f\u00fcr die selbst\u00e4ndige T\u00e4tigkeit essenziell. Ich zeige, welche Vorgehensweise f\u00fcr mich gut funktioniert.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/getgrip.de\/blog\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aufgabenverwaltung: mehr Produktivit\u00e4t f\u00fcr selbst\u00e4ndige Webdesigner\" \/>\n<meta property=\"og:description\" content=\"Eine zuverl\u00e4ssige Aufgabenverwaltung zu haben, ist f\u00fcr die selbst\u00e4ndige T\u00e4tigkeit essenziell. Ich zeige, welche Vorgehensweise f\u00fcr mich gut funktioniert.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/getgrip.de\/blog\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\/\" \/>\n<meta property=\"og:site_name\" content=\"Grip Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grip.angebotssoftware\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/grip.angebotssoftware\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-03T23:11:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-13T13:13:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/getgrip.de\/blog\/wp-content\/uploads\/2015\/11\/trello_board.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"651\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Till\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@till_otto\" \/>\n<meta name=\"twitter:site\" content=\"@grip_app\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Till\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\\\/\"},\"author\":{\"name\":\"Till\",\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/#\\\/schema\\\/person\\\/50f29e3e3c20f6ef95d856e2e3800271\"},\"headline\":\"Aufgabenverwaltung: mit Trello in wenigen Schritten zu mehr Produktivit\u00e4t\",\"datePublished\":\"2014-01-03T23:11:16+00:00\",\"dateModified\":\"2024-11-13T13:13:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\\\/\"},\"wordCount\":1053,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/trello_board.png\",\"articleSection\":[\"Selbst\u00e4ndigkeit\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/getgrip.de\\\/blog\\\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\\\/\",\"url\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\\\/\",\"name\":\"Aufgabenverwaltung: mehr Produktivit\u00e4t f\u00fcr selbst\u00e4ndige Webdesigner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/trello_board.png\",\"datePublished\":\"2014-01-03T23:11:16+00:00\",\"dateModified\":\"2024-11-13T13:13:53+00:00\",\"description\":\"Eine zuverl\u00e4ssige Aufgabenverwaltung zu haben, ist f\u00fcr die selbst\u00e4ndige T\u00e4tigkeit essenziell. Ich zeige, welche Vorgehensweise f\u00fcr mich gut funktioniert.\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/getgrip.de\\\/blog\\\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/trello_board.png\",\"contentUrl\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/trello_board.png\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/\",\"name\":\"Grip Blog\",\"description\":\"Professionelle Angebote schreiben. In Rekordzeit.\",\"publisher\":{\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/#organization\",\"name\":\"Grip by T8 Lab GmbH\",\"url\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/grip_inverse_sm.png\",\"contentUrl\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/grip_inverse_sm.png\",\"width\":200,\"height\":51,\"caption\":\"Grip by T8 Lab GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/grip.angebotssoftware\",\"https:\\\/\\\/x.com\\\/grip_app\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/#\\\/schema\\\/person\\\/50f29e3e3c20f6ef95d856e2e3800271\",\"name\":\"Till\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f7ba97ed860e69dc3929a8be0690ef648f87ebbc6a181bf1aabefcc51524d73?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f7ba97ed860e69dc3929a8be0690ef648f87ebbc6a181bf1aabefcc51524d73?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f7ba97ed860e69dc3929a8be0690ef648f87ebbc6a181bf1aabefcc51524d73?s=96&d=mm&r=g\",\"caption\":\"Till\"},\"description\":\"Till Otto ist der Gr\u00fcnder von Grip und seit \u00fcber 10 Jahren als Softwareentwickler und Berater selbst\u00e4ndig.\",\"sameAs\":[\"https:\\\/\\\/getgrip.de\\\/?utm_source=asnet&amp;utm_medium=blog&amp;utm_content=author&amp;utm\",\"https:\\\/\\\/www.facebook.com\\\/grip.angebotssoftware\",\"https:\\\/\\\/x.com\\\/till_otto\"],\"url\":\"https:\\\/\\\/getgrip.de\\\/blog\\\/author\\\/till\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aufgabenverwaltung: mehr Produktivit\u00e4t f\u00fcr selbst\u00e4ndige Webdesigner","description":"Eine zuverl\u00e4ssige Aufgabenverwaltung zu haben, ist f\u00fcr die selbst\u00e4ndige T\u00e4tigkeit essenziell. Ich zeige, welche Vorgehensweise f\u00fcr mich gut funktioniert.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/getgrip.de\/blog\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\/","og_locale":"de_DE","og_type":"article","og_title":"Aufgabenverwaltung: mehr Produktivit\u00e4t f\u00fcr selbst\u00e4ndige Webdesigner","og_description":"Eine zuverl\u00e4ssige Aufgabenverwaltung zu haben, ist f\u00fcr die selbst\u00e4ndige T\u00e4tigkeit essenziell. Ich zeige, welche Vorgehensweise f\u00fcr mich gut funktioniert.","og_url":"https:\/\/getgrip.de\/blog\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\/","og_site_name":"Grip Blog","article_publisher":"https:\/\/www.facebook.com\/grip.angebotssoftware","article_author":"https:\/\/www.facebook.com\/grip.angebotssoftware","article_published_time":"2014-01-03T23:11:16+00:00","article_modified_time":"2024-11-13T13:13:53+00:00","og_image":[{"width":1440,"height":651,"url":"https:\/\/getgrip.de\/blog\/wp-content\/uploads\/2015\/11\/trello_board.png","type":"image\/png"}],"author":"Till","twitter_card":"summary_large_image","twitter_creator":"@till_otto","twitter_site":"@grip_app","twitter_misc":{"Verfasst von":"Till","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/getgrip.de\/blog\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\/#article","isPartOf":{"@id":"https:\/\/getgrip.de\/blog\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\/"},"author":{"name":"Till","@id":"https:\/\/getgrip.de\/blog\/#\/schema\/person\/50f29e3e3c20f6ef95d856e2e3800271"},"headline":"Aufgabenverwaltung: mit Trello in wenigen Schritten zu mehr Produktivit\u00e4t","datePublished":"2014-01-03T23:11:16+00:00","dateModified":"2024-11-13T13:13:53+00:00","mainEntityOfPage":{"@id":"https:\/\/getgrip.de\/blog\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\/"},"wordCount":1053,"commentCount":2,"publisher":{"@id":"https:\/\/getgrip.de\/blog\/#organization"},"image":{"@id":"https:\/\/getgrip.de\/blog\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\/#primaryimage"},"thumbnailUrl":"https:\/\/getgrip.de\/blog\/wp-content\/uploads\/2015\/11\/trello_board.png","articleSection":["Selbst\u00e4ndigkeit"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/getgrip.de\/blog\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/getgrip.de\/blog\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\/","url":"https:\/\/getgrip.de\/blog\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\/","name":"Aufgabenverwaltung: mehr Produktivit\u00e4t f\u00fcr selbst\u00e4ndige Webdesigner","isPartOf":{"@id":"https:\/\/getgrip.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/getgrip.de\/blog\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\/#primaryimage"},"image":{"@id":"https:\/\/getgrip.de\/blog\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\/#primaryimage"},"thumbnailUrl":"https:\/\/getgrip.de\/blog\/wp-content\/uploads\/2015\/11\/trello_board.png","datePublished":"2014-01-03T23:11:16+00:00","dateModified":"2024-11-13T13:13:53+00:00","description":"Eine zuverl\u00e4ssige Aufgabenverwaltung zu haben, ist f\u00fcr die selbst\u00e4ndige T\u00e4tigkeit essenziell. Ich zeige, welche Vorgehensweise f\u00fcr mich gut funktioniert.","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/getgrip.de\/blog\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/getgrip.de\/blog\/aufgabenverwaltung-mit-trello-in-wenigen-schritten-zu-mehr-produktivitaet\/#primaryimage","url":"https:\/\/getgrip.de\/blog\/wp-content\/uploads\/2015\/11\/trello_board.png","contentUrl":"https:\/\/getgrip.de\/blog\/wp-content\/uploads\/2015\/11\/trello_board.png"},{"@type":"WebSite","@id":"https:\/\/getgrip.de\/blog\/#website","url":"https:\/\/getgrip.de\/blog\/","name":"Grip Blog","description":"Professionelle Angebote schreiben. In Rekordzeit.","publisher":{"@id":"https:\/\/getgrip.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/getgrip.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/getgrip.de\/blog\/#organization","name":"Grip by T8 Lab GmbH","url":"https:\/\/getgrip.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/getgrip.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/getgrip.de\/blog\/wp-content\/uploads\/2016\/01\/grip_inverse_sm.png","contentUrl":"https:\/\/getgrip.de\/blog\/wp-content\/uploads\/2016\/01\/grip_inverse_sm.png","width":200,"height":51,"caption":"Grip by T8 Lab GmbH"},"image":{"@id":"https:\/\/getgrip.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/grip.angebotssoftware","https:\/\/x.com\/grip_app"]},{"@type":"Person","@id":"https:\/\/getgrip.de\/blog\/#\/schema\/person\/50f29e3e3c20f6ef95d856e2e3800271","name":"Till","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5f7ba97ed860e69dc3929a8be0690ef648f87ebbc6a181bf1aabefcc51524d73?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5f7ba97ed860e69dc3929a8be0690ef648f87ebbc6a181bf1aabefcc51524d73?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f7ba97ed860e69dc3929a8be0690ef648f87ebbc6a181bf1aabefcc51524d73?s=96&d=mm&r=g","caption":"Till"},"description":"Till Otto ist der Gr\u00fcnder von Grip und seit \u00fcber 10 Jahren als Softwareentwickler und Berater selbst\u00e4ndig.","sameAs":["https:\/\/getgrip.de\/?utm_source=asnet&amp;utm_medium=blog&amp;utm_content=author&amp;utm","https:\/\/www.facebook.com\/grip.angebotssoftware","https:\/\/x.com\/till_otto"],"url":"https:\/\/getgrip.de\/blog\/author\/till\/"}]}},"_links":{"self":[{"href":"https:\/\/getgrip.de\/blog\/wp-json\/wp\/v2\/posts\/447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/getgrip.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/getgrip.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/getgrip.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/getgrip.de\/blog\/wp-json\/wp\/v2\/comments?post=447"}],"version-history":[{"count":15,"href":"https:\/\/getgrip.de\/blog\/wp-json\/wp\/v2\/posts\/447\/revisions"}],"predecessor-version":[{"id":1809,"href":"https:\/\/getgrip.de\/blog\/wp-json\/wp\/v2\/posts\/447\/revisions\/1809"}],"wp:attachment":[{"href":"https:\/\/getgrip.de\/blog\/wp-json\/wp\/v2\/media?parent=447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/getgrip.de\/blog\/wp-json\/wp\/v2\/categories?post=447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/getgrip.de\/blog\/wp-json\/wp\/v2\/tags?post=447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}